{"id":349278,"date":"2021-06-03T08:59:33","date_gmt":"2021-06-03T06:59:33","guid":{"rendered":"https:\/\/cnsfg.cat\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/"},"modified":"2022-06-20T14:58:11","modified_gmt":"2022-06-20T12:58:11","slug":"wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona","status":"publish","type":"post","link":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/","title":{"rendered":"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.14.7&#8243; hover_enabled=&#8220;0&#8243; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; custom_padding=&#8220;0px||||false|false&#8220; min_height=&#8220;0px&#8220; sticky_enabled=&#8220;0&#8243; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.14.7&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;3.27.4&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]Er <strong>Wassersportclub Sant Feliu de Gu\u00edxols<\/strong> hat wieder mit der zusammengearbeitet <a href=\"https:\/\/www.fundacioudg.org\/es\/master-emergencies-urgencies.html\">Meister f\u00fcr Notf\u00e4lle und Notf\u00e4lle<\/a> des <strong>Universit\u00e4t Girona<\/strong> zum Hauptsitz der nautischen \u00dcbungen dieser Ausbildung, die sich an Universit\u00e4tsabsolventen der Medizin und Pflege richtet, um ihnen Werkzeuge zu geben, um in Dringlichkeitssituationen, Notf\u00e4llen und Katastrophen in den verschiedenen Bereichen der Versorgung zu reagieren. Das Mitglied und Vorstandsmitglied Pere Rimbau ist einer der Hauptverantwortlichen dieser Formation.<\/p>\n<h3>Rettungs-, Abschlepp- und Wasseraufbereitungstechniken<\/h3>\n<p>W\u00e4hrend der Aktivit\u00e4t werden Themen wie Rettungstechniken, Schleppen und Behandlung im Wasser oder neue innovative Materialien f\u00fcr die Wasserrettung vermittelt.<\/p>\n<p>Neben dem Nautikclub Sant Feliu de Gu\u00edxols haben sie mit dem Master-Diplom Piscis Diving, der Nautischen Schule Medi\u00f1\u00e0, der Feuerwehr und dem Krankenhaus Palam\u00f3s zusammengearbeitet.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Er Wassersportclub Sant Feliu de Gu\u00edxols hat wieder mit der zusammengearbeitet Meister f\u00fcr Notf\u00e4lle und Notf\u00e4lle des Universit\u00e4t Girona zum Hauptsitz der nautischen \u00dcbungen dieser Ausbildung, die sich an Universit\u00e4tsabsolventen [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":348300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[274],"tags":[279],"class_list":["post-349278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-sicherheit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona - Club N\u00e0utic Sant Feliu de Guixols<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona - Club N\u00e0utic Sant Feliu de Guixols\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic Sant Feliu de Guixols\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Club-N%c3%a0utic-Sant-Feliu-525823567569507\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-03T06:59:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-20T12:58:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnsfg.cat\/wp-content\/uploads\/2021\/06\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Muriel De Jong\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NauticSantFeliu\" \/>\n<meta name=\"twitter:site\" content=\"@NauticSantFeliu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/\"},\"author\":{\"name\":\"Muriel De Jong\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/person\\\/55df709ae42148f6126825d43278d2f3\"},\"headline\":\"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona\",\"datePublished\":\"2021-06-03T06:59:33+00:00\",\"dateModified\":\"2022-06-20T12:58:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg\",\"keywords\":[\"Sicherheit\"],\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/\",\"name\":\"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona - Club N\u00e0utic Sant Feliu de Guixols\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg\",\"datePublished\":\"2021-06-03T06:59:33+00:00\",\"dateModified\":\"2022-06-20T12:58:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg\",\"width\":1800,\"height\":1350,\"caption\":\"CNSFG Master Notfall und Notf\u00e4lle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/\",\"name\":\"Club N\u00e0utic Sant Feliu de Guixols\",\"description\":\"Club n\u00e0utic amb m\u00e9s de 400 amarradors a Sant Feliu de Guixols, Costa Brava.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#organization\",\"name\":\"Club Na\u00f9tic Sant Feliu de Guixols\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_CNSFG_180.png\",\"contentUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_CNSFG_180.png\",\"width\":180,\"height\":71,\"caption\":\"Club Na\u00f9tic Sant Feliu de Guixols\"},\"image\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Club-N\u00e0utic-Sant-Feliu-525823567569507\\\/\",\"https:\\\/\\\/x.com\\\/NauticSantFeliu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/person\\\/55df709ae42148f6126825d43278d2f3\",\"name\":\"Muriel De Jong\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c526856dc32b071bfa579fa4c5a2de001bcc4db7d16bfe78da4798d5e1f1eba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c526856dc32b071bfa579fa4c5a2de001bcc4db7d16bfe78da4798d5e1f1eba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c526856dc32b071bfa579fa4c5a2de001bcc4db7d16bfe78da4798d5e1f1eba?s=96&d=mm&r=g\",\"caption\":\"Muriel De Jong\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona - Club N\u00e0utic Sant Feliu de Guixols","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/","og_locale":"de_DE","og_type":"article","og_title":"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona - Club N\u00e0utic Sant Feliu de Guixols","og_url":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/","og_site_name":"Club N\u00e0utic Sant Feliu de Guixols","article_publisher":"https:\/\/www.facebook.com\/Club-N%c3%a0utic-Sant-Feliu-525823567569507\/","article_published_time":"2021-06-03T06:59:33+00:00","article_modified_time":"2022-06-20T12:58:11+00:00","og_image":[{"width":1800,"height":1350,"url":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2021\/06\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg","type":"image\/jpeg"}],"author":"Muriel De Jong","twitter_card":"summary_large_image","twitter_creator":"@NauticSantFeliu","twitter_site":"@NauticSantFeliu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#article","isPartOf":{"@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/"},"author":{"name":"Muriel De Jong","@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/person\/55df709ae42148f6126825d43278d2f3"},"headline":"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona","datePublished":"2021-06-03T06:59:33+00:00","dateModified":"2022-06-20T12:58:11+00:00","mainEntityOfPage":{"@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/cnsfg.cat\/de\/#organization"},"image":{"@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2021\/06\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg","keywords":["Sicherheit"],"articleSection":["Nachrichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/","url":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/","name":"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona - Club N\u00e0utic Sant Feliu de Guixols","isPartOf":{"@id":"https:\/\/cnsfg.cat\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#primaryimage"},"image":{"@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2021\/06\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg","datePublished":"2021-06-03T06:59:33+00:00","dateModified":"2022-06-20T12:58:11+00:00","breadcrumb":{"@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#primaryimage","url":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2021\/06\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg","contentUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2021\/06\/WhatsApp-Image-2021-06-02-at-14.58.46-1.jpeg","width":1800,"height":1350,"caption":"CNSFG Master Notfall und Notf\u00e4lle"},{"@type":"BreadcrumbList","@id":"https:\/\/cnsfg.cat\/de\/wir-kooperieren-wieder-mit-dem-master-in-emergencies-and-emergencies-der-universitaet-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cnsfg.cat\/de\/"},{"@type":"ListItem","position":2,"name":"Wir kooperieren wieder mit dem Master in Emergencies and Emergencies der Universit\u00e4t Girona"}]},{"@type":"WebSite","@id":"https:\/\/cnsfg.cat\/de\/#website","url":"https:\/\/cnsfg.cat\/de\/","name":"Club N\u00e0utic Sant Feliu de Guixols","description":"Club n\u00e0utic amb m\u00e9s de 400 amarradors a Sant Feliu de Guixols, Costa Brava.","publisher":{"@id":"https:\/\/cnsfg.cat\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnsfg.cat\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cnsfg.cat\/de\/#organization","name":"Club Na\u00f9tic Sant Feliu de Guixols","url":"https:\/\/cnsfg.cat\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/logo\/image\/","url":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2020\/03\/LOGO_CNSFG_180.png","contentUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2020\/03\/LOGO_CNSFG_180.png","width":180,"height":71,"caption":"Club Na\u00f9tic Sant Feliu de Guixols"},"image":{"@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Club-N\u00e0utic-Sant-Feliu-525823567569507\/","https:\/\/x.com\/NauticSantFeliu"]},{"@type":"Person","@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/person\/55df709ae42148f6126825d43278d2f3","name":"Muriel De Jong","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/2c526856dc32b071bfa579fa4c5a2de001bcc4db7d16bfe78da4798d5e1f1eba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c526856dc32b071bfa579fa4c5a2de001bcc4db7d16bfe78da4798d5e1f1eba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c526856dc32b071bfa579fa4c5a2de001bcc4db7d16bfe78da4798d5e1f1eba?s=96&d=mm&r=g","caption":"Muriel De Jong"}}]}},"_links":{"self":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/posts\/349278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/comments?post=349278"}],"version-history":[{"count":0,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/posts\/349278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/media\/348300"}],"wp:attachment":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/media?parent=349278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/categories?post=349278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/tags?post=349278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}