{"id":372305,"date":"2022-08-11T13:48:12","date_gmt":"2022-08-11T11:48:12","guid":{"rendered":"https:\/\/cnsfg.cat\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/"},"modified":"2022-08-11T13:48:12","modified_gmt":"2022-08-11T11:48:12","slug":"riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen","status":"publish","type":"post","link":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/","title":{"rendered":"Riesiges Sommeressen und Lieferung von silbernen Abzeichen"},"content":{"rendered":"<p>131 Mitglieder des <strong>Sant Feliu de Gu\u00edxols Yacht Club<\/strong> trafen sich an diesem Mittwoch, dem 10. August, auf der Terrasse des Unternehmens, um das <strong>gesellige Abendessen im Sommer<\/strong> zu genie\u00dfen. Eine ganz besondere Veranstaltung, die die gesamte CNSFG-Familie zusammenbringt und bei der die emblematischen <strong>silbernen Abzeichen<\/strong> an die Mitarbeiter verliehen werden, die seit 40 Jahren Teil des Unternehmens sind. Bei dieser Gelegenheit sammelten sie die Abzeichen: <strong>Javier De Blas<\/strong>, <strong>Jos\u00e9 F\u00e9lix Donaci\u00f3<\/strong>, <strong>Jacinto Agust\u00ed<\/strong>,<strong> Josep Pujol<\/strong> und <strong>Antoni Durall<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-372278\" src=\"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\"><\/p>\n<h3>Solidarit\u00e4tscheck und dekorierter Bootswettbewerb<\/h3>\n<p>Im Rahmen des Abends wurde der<strong> Scheck \u00fcber 6.000 Euro, der im vergangenen Juli auf der <a href=\"https:\/\/cnsfg.cat\/festa-blanc-negre-2022\/\">White &amp; Black Solidarity Party<\/a> gesammelt wurde<\/strong>, auch an die <a href=\"https:\/\/www.fundaciovimar.org\/\">VIMAR Foundation<\/a> \u00fcbergeben. Die Spende wurde von ihrem Schatzmeister und M\u00e4zen Raimon Sarret und ihrer Schirmherrin Margarita Flaqu\u00e9 gesammelt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-372289\" src=\"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\"><\/p>\n<p>Schlie\u00dflich wurde auch der Preis des am besten dekorierten Bootswettbewerbs der Feier der <a href=\"https:\/\/cnsfg.cat\/club-nautic-carme-sant-feliu\/\">Jungfrau von Carmen<\/a> im Jahr 2022 verliehen, der vom Partner <strong>Llu\u00eds Donat<\/strong> gewonnen wurde. Der Preis wurde von seiner Frau Marta Llin\u00e0s und seinem Sohn Mart\u00ed Donat entgegengenommen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-372283\" src=\"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\"><\/p>\n<p>Das sommerliche Social Dinner war sehr lebhaft und endete mit einer musikalischen Session von DJ \u00c0lex, die alle Teilnehmer zum Tanzen brachte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>131 Mitglieder des Sant Feliu de Gu\u00edxols Yacht Club trafen sich an diesem Mittwoch, dem 10. August, auf der Terrasse des Unternehmens, um das gesellige Abendessen im Sommer zu genie\u00dfen. [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":372273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[323,521],"tags":[683,702,825,824],"class_list":["post-372305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktivitaten","category-partners","tag-club-nautic-de","tag-partner","tag-silberne-insignien","tag-sommer-dinner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riesiges Sommeressen und Lieferung von silbernen Abzeichen - Club N\u00e0utic Sant Feliu de Guixols<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riesiges Sommeressen und Lieferung von silbernen Abzeichen - Club N\u00e0utic Sant Feliu de Guixols\" \/>\n<meta property=\"og:description\" content=\"131 Mitglieder des Sant Feliu de Gu\u00edxols Yacht Club trafen sich an diesem Mittwoch, dem 10. August, auf der Terrasse des Unternehmens, um das gesellige Abendessen im Sommer zu genie\u00dfen. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic Sant Feliu de Guixols\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Club-N%c3%a0utic-Sant-Feliu-525823567569507\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T11:48:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joana Valent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NauticSantFeliu\" \/>\n<meta name=\"twitter:site\" content=\"@NauticSantFeliu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/\"},\"author\":{\"name\":\"Joana Valent\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/person\\\/4692ae1497c51d70b33ac922e8c6c488\"},\"headline\":\"Riesiges Sommeressen und Lieferung von silbernen Abzeichen\",\"datePublished\":\"2022-08-11T11:48:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/sopar-social-0.jpg\",\"keywords\":[\"club n\u00e0utic\",\"Partner\",\"Silberne Insignien\",\"Sommer-Dinner\"],\"articleSection\":[\"Aktivit\u00e4ten\",\"Partners\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/\",\"name\":\"Riesiges Sommeressen und Lieferung von silbernen Abzeichen - Club N\u00e0utic Sant Feliu de Guixols\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/sopar-social-0.jpg\",\"datePublished\":\"2022-08-11T11:48:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/sopar-social-0.jpg\",\"contentUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/sopar-social-0.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riesiges Sommeressen und Lieferung von silbernen Abzeichen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/\",\"name\":\"Club N\u00e0utic Sant Feliu de Guixols\",\"description\":\"Club n\u00e0utic amb m\u00e9s de 400 amarradors a Sant Feliu de Guixols, Costa Brava.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#organization\",\"name\":\"Club Na\u00f9tic Sant Feliu de Guixols\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_CNSFG_180.png\",\"contentUrl\":\"https:\\\/\\\/cnsfg.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_CNSFG_180.png\",\"width\":180,\"height\":71,\"caption\":\"Club Na\u00f9tic Sant Feliu de Guixols\"},\"image\":{\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Club-N\u00e0utic-Sant-Feliu-525823567569507\\\/\",\"https:\\\/\\\/x.com\\\/NauticSantFeliu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnsfg.cat\\\/de\\\/#\\\/schema\\\/person\\\/4692ae1497c51d70b33ac922e8c6c488\",\"name\":\"Joana Valent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f78539fa1bea92ad6051500b1db1b0b36a8ee6743e42e6d8515ef5eee33904b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f78539fa1bea92ad6051500b1db1b0b36a8ee6743e42e6d8515ef5eee33904b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f78539fa1bea92ad6051500b1db1b0b36a8ee6743e42e6d8515ef5eee33904b?s=96&d=mm&r=g\",\"caption\":\"Joana Valent\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riesiges Sommeressen und Lieferung von silbernen Abzeichen - Club N\u00e0utic Sant Feliu de Guixols","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/","og_locale":"de_DE","og_type":"article","og_title":"Riesiges Sommeressen und Lieferung von silbernen Abzeichen - Club N\u00e0utic Sant Feliu de Guixols","og_description":"131 Mitglieder des Sant Feliu de Gu\u00edxols Yacht Club trafen sich an diesem Mittwoch, dem 10. August, auf der Terrasse des Unternehmens, um das gesellige Abendessen im Sommer zu genie\u00dfen. [&hellip;]","og_url":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/","og_site_name":"Club N\u00e0utic Sant Feliu de Guixols","article_publisher":"https:\/\/www.facebook.com\/Club-N%c3%a0utic-Sant-Feliu-525823567569507\/","article_published_time":"2022-08-11T11:48:12+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-0.jpg","type":"image\/jpeg"}],"author":"Joana Valent","twitter_card":"summary_large_image","twitter_creator":"@NauticSantFeliu","twitter_site":"@NauticSantFeliu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#article","isPartOf":{"@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/"},"author":{"name":"Joana Valent","@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/person\/4692ae1497c51d70b33ac922e8c6c488"},"headline":"Riesiges Sommeressen und Lieferung von silbernen Abzeichen","datePublished":"2022-08-11T11:48:12+00:00","mainEntityOfPage":{"@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/cnsfg.cat\/de\/#organization"},"image":{"@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#primaryimage"},"thumbnailUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-0.jpg","keywords":["club n\u00e0utic","Partner","Silberne Insignien","Sommer-Dinner"],"articleSection":["Aktivit\u00e4ten","Partners"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/","url":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/","name":"Riesiges Sommeressen und Lieferung von silbernen Abzeichen - Club N\u00e0utic Sant Feliu de Guixols","isPartOf":{"@id":"https:\/\/cnsfg.cat\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#primaryimage"},"image":{"@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#primaryimage"},"thumbnailUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-0.jpg","datePublished":"2022-08-11T11:48:12+00:00","breadcrumb":{"@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#primaryimage","url":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-0.jpg","contentUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2022\/08\/sopar-social-0.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/cnsfg.cat\/de\/riesiges-sommeressen-und-lieferung-von-silbernen-abzeichen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cnsfg.cat\/de\/"},{"@type":"ListItem","position":2,"name":"Riesiges Sommeressen und Lieferung von silbernen Abzeichen"}]},{"@type":"WebSite","@id":"https:\/\/cnsfg.cat\/de\/#website","url":"https:\/\/cnsfg.cat\/de\/","name":"Club N\u00e0utic Sant Feliu de Guixols","description":"Club n\u00e0utic amb m\u00e9s de 400 amarradors a Sant Feliu de Guixols, Costa Brava.","publisher":{"@id":"https:\/\/cnsfg.cat\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnsfg.cat\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cnsfg.cat\/de\/#organization","name":"Club Na\u00f9tic Sant Feliu de Guixols","url":"https:\/\/cnsfg.cat\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/logo\/image\/","url":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2020\/03\/LOGO_CNSFG_180.png","contentUrl":"https:\/\/cnsfg.cat\/wp-content\/uploads\/2020\/03\/LOGO_CNSFG_180.png","width":180,"height":71,"caption":"Club Na\u00f9tic Sant Feliu de Guixols"},"image":{"@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Club-N\u00e0utic-Sant-Feliu-525823567569507\/","https:\/\/x.com\/NauticSantFeliu"]},{"@type":"Person","@id":"https:\/\/cnsfg.cat\/de\/#\/schema\/person\/4692ae1497c51d70b33ac922e8c6c488","name":"Joana Valent","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5f78539fa1bea92ad6051500b1db1b0b36a8ee6743e42e6d8515ef5eee33904b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f78539fa1bea92ad6051500b1db1b0b36a8ee6743e42e6d8515ef5eee33904b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f78539fa1bea92ad6051500b1db1b0b36a8ee6743e42e6d8515ef5eee33904b?s=96&d=mm&r=g","caption":"Joana Valent"}}]}},"_links":{"self":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/posts\/372305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/comments?post=372305"}],"version-history":[{"count":0,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/posts\/372305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/media\/372273"}],"wp:attachment":[{"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/media?parent=372305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/categories?post=372305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnsfg.cat\/de\/wp-json\/wp\/v2\/tags?post=372305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}